{"id":43,"count":5,"description":"","link":"https:\/\/praditadirgantara.sch.id\/id\/event_listing_category\/science-technology\/","name":"Science &amp; Technology","slug":"science-technology","taxonomy":"event_listing_category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Science &amp; Technology Archives - SMA Pradita Dirgantara<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/praditadirgantara.sch.id\/id\/event_listing_category\/science-technology\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Science &amp; Technology Archives - SMA Pradita Dirgantara\" \/>\n<meta property=\"og:url\" content=\"https:\/\/praditadirgantara.sch.id\/id\/event_listing_category\/science-technology\/\" \/>\n<meta property=\"og:site_name\" content=\"SMA Pradita Dirgantara\" \/>\n<meta property=\"og:image\" content=\"https:\/\/praditadirgantara.sch.id\/wp-content\/uploads\/2023\/11\/Logo-Pradita-Dirgantara.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@smapradita\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/praditadirgantara.sch.id\\\/event_listing_category\\\/science-technology\\\/\",\"url\":\"https:\\\/\\\/praditadirgantara.sch.id\\\/event_listing_category\\\/science-technology\\\/\",\"name\":\"Science &amp; Technology Archives - SMA Pradita Dirgantara\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/praditadirgantara.sch.id\\\/id\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/praditadirgantara.sch.id\\\/event_listing_category\\\/science-technology\\\/#breadcrumb\"},\"inLanguage\":\"id\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/praditadirgantara.sch.id\\\/event_listing_category\\\/science-technology\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/praditadirgantara.sch.id\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Science &amp; Technology\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/praditadirgantara.sch.id\\\/id\\\/#website\",\"url\":\"https:\\\/\\\/praditadirgantara.sch.id\\\/id\\\/\",\"name\":\"SMA Pradita Dirgantara\",\"description\":\"SMA Pradita Dirgantara, Kurikulum International Baccalaureate\",\"publisher\":{\"@id\":\"https:\\\/\\\/praditadirgantara.sch.id\\\/id\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/praditadirgantara.sch.id\\\/id\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/praditadirgantara.sch.id\\\/id\\\/#organization\",\"name\":\"SMA Pradita Dirgantara\",\"url\":\"https:\\\/\\\/praditadirgantara.sch.id\\\/id\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/praditadirgantara.sch.id\\\/id\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/praditadirgantara.sch.id\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-Logo-Pradita-Dirgantara.webp\",\"contentUrl\":\"https:\\\/\\\/praditadirgantara.sch.id\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-Logo-Pradita-Dirgantara.webp\",\"width\":150,\"height\":150,\"caption\":\"SMA Pradita Dirgantara\"},\"image\":{\"@id\":\"https:\\\/\\\/praditadirgantara.sch.id\\\/id\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/smapradita\",\"https:\\\/\\\/x.com\\\/smapradita\",\"https:\\\/\\\/www.instagram.com\\\/smapraditadirgantara\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/smapraditadirgantara\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@smapraditadirgantara\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Science &amp; Technology Archives - SMA Pradita Dirgantara","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/praditadirgantara.sch.id\/id\/event_listing_category\/science-technology\/","og_locale":"id_ID","og_type":"article","og_title":"Science &amp; Technology Archives - SMA Pradita Dirgantara","og_url":"https:\/\/praditadirgantara.sch.id\/id\/event_listing_category\/science-technology\/","og_site_name":"SMA Pradita Dirgantara","og_image":[{"width":150,"height":150,"url":"https:\/\/praditadirgantara.sch.id\/wp-content\/uploads\/2023\/11\/Logo-Pradita-Dirgantara.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@smapradita","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/praditadirgantara.sch.id\/event_listing_category\/science-technology\/","url":"https:\/\/praditadirgantara.sch.id\/event_listing_category\/science-technology\/","name":"Science &amp; Technology Archives - SMA Pradita Dirgantara","isPartOf":{"@id":"https:\/\/praditadirgantara.sch.id\/id\/#website"},"breadcrumb":{"@id":"https:\/\/praditadirgantara.sch.id\/event_listing_category\/science-technology\/#breadcrumb"},"inLanguage":"id"},{"@type":"BreadcrumbList","@id":"https:\/\/praditadirgantara.sch.id\/event_listing_category\/science-technology\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/praditadirgantara.sch.id\/"},{"@type":"ListItem","position":2,"name":"Science &amp; Technology"}]},{"@type":"WebSite","@id":"https:\/\/praditadirgantara.sch.id\/id\/#website","url":"https:\/\/praditadirgantara.sch.id\/id\/","name":"SMA Pradita Dirgantara","description":"SMA Pradita Dirgantara, Kurikulum International Baccalaureate","publisher":{"@id":"https:\/\/praditadirgantara.sch.id\/id\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/praditadirgantara.sch.id\/id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/praditadirgantara.sch.id\/id\/#organization","name":"SMA Pradita Dirgantara","url":"https:\/\/praditadirgantara.sch.id\/id\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/praditadirgantara.sch.id\/id\/#\/schema\/logo\/image\/","url":"https:\/\/praditadirgantara.sch.id\/wp-content\/uploads\/2023\/11\/cropped-Logo-Pradita-Dirgantara.webp","contentUrl":"https:\/\/praditadirgantara.sch.id\/wp-content\/uploads\/2023\/11\/cropped-Logo-Pradita-Dirgantara.webp","width":150,"height":150,"caption":"SMA Pradita Dirgantara"},"image":{"@id":"https:\/\/praditadirgantara.sch.id\/id\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/smapradita","https:\/\/x.com\/smapradita","https:\/\/www.instagram.com\/smapraditadirgantara\/","https:\/\/www.linkedin.com\/company\/smapraditadirgantara\/","https:\/\/www.tiktok.com\/@smapraditadirgantara"]}]}},"_links":{"self":[{"href":"https:\/\/praditadirgantara.sch.id\/id\/wp-json\/wp\/v2\/event_listing_category\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/praditadirgantara.sch.id\/id\/wp-json\/wp\/v2\/event_listing_category"}],"about":[{"href":"https:\/\/praditadirgantara.sch.id\/id\/wp-json\/wp\/v2\/taxonomies\/event_listing_category"}],"wp:post_type":[{"href":"https:\/\/praditadirgantara.sch.id\/id\/wp-json\/wp\/v2\/event_listing?event_listing_category=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}